{"id":30343,"date":"2023-03-31T11:11:03","date_gmt":"2023-03-31T09:11:03","guid":{"rendered":"https:\/\/costablancabuyers.com\/?post_type=property&#038;p=30343"},"modified":"2026-05-10T01:15:58","modified_gmt":"2026-05-09T23:15:58","slug":"6461alc-villa-en-alcalali","status":"publish","type":"property","link":"https:\/\/costablancabuyers.com\/es\/property\/6461alc-villa-en-alcalali\/","title":{"rendered":"Villa en Alcalali"},"content":{"rendered":"<p>Este precioso chalet de una sola planta de nueva construcci\u00f3n est\u00e1 situado en una zona tranquila de una urbanizaci\u00f3n de Alcalali. Por un lado, el chalet ofrece un amplio sal\u00f3n con zona de comedor, una cocina moderna totalmente equipada y un lavadero. En el otro lado est\u00e1n los 2 dormitorios dobles, un cuarto de ba\u00f1o y el dormitorio principal con ba\u00f1o en suite. Adem\u00e1s, la villa tiene una amplia terraza con piscina y hay varias otras zonas de estar alrededor de la villa desde donde puedes disfrutar de las hermosas vistas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Este precioso chalet de una sola planta de nueva construcci\u00f3n est\u00e1 situado en una zona tranquila de una urbanizaci\u00f3n de Alcalali. Por un lado, el chalet ofrece un amplio sal\u00f3n con zona de comedor, una cocina moderna totalmente equipada y un lavadero. En el otro lado est\u00e1n los 2 dormitorios dobles, un cuarto de ba\u00f1o [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":31722,"parent":0,"menu_order":0,"template":"","property_type":[231],"property_status":[777],"property_feature":[232,233,273,264,256,235,236,259,269,237,238],"property_label":[],"property_country":[226],"property_state":[227],"property_city":[295],"property_area":[796],"class_list":["post-30343","property","type-property","status-publish","has-post-thumbnail","hentry","property_type-villa","property_status-nueva-construccion","property_feature-aire-acondicionado","property_feature-armarios-empotrados","property_feature-bomba-de-calor","property_feature-calefaccion-por-suelo-radiante","property_feature-cochera","property_feature-doble-acristalamiento","property_feature-jardin","property_feature-persianas-electricas","property_feature-piscina","property_feature-terraza","property_feature-trastero","property_country-espana","property_state-alicante","property_city-alcalali","property_area-alcalali"],"property_meta":{"_wp_old_slug":["6461alc-villa-en-alcalali"],"fave_currency":["EUR"],"fave_currency_info":[""],"fave_property_price":["645000"],"fave_property_size":["149"],"fave_property_land":["830"],"fave_property_bedrooms":["3"],"fave_property_bathrooms":["2"],"fave_property_garage":["2"],"fave_property_map":["0"],"fave_property_id":["6461ALC"],"fave_property_year":["2023"],"fave_property_address":["Alcalali"],"fave_property_zip":["03728"],"fave_property_country":["ES"],"fave_featured":["0"],"houzez_featured_listing_date":[""],"fave_agent_display_option":["author_info"],"fave_prop_homeslider":["no"],"fave_additional_features_enable":["disable"],"floor_plans":[null],"fave_multi_units":[null],"additional_features":[null],"fave_agents":["14273"],"fave_property_agency":["9002"],"fave_property_map_address":[""],"fave_property_location":["0,0"],"houzez_geolocation_lat":["0"],"houzez_geolocation_long":["0"],"_yoast_wpseo_focuskw_text_input":[""],"_yoast_wpseo_title":["6461ALC Moderno chalet de nueva construcci\u00f3n de una sola planta en venta en Alcalali"],"_yoast_wpseo_opengraph-title":["6461ALC Moderno chalet de nueva construcci\u00f3n de una sola planta en venta en Alcalali"],"_yoast_wpseo_twitter-title":["6461ALC Moderno chalet de nueva construcci\u00f3n de una sola planta en venta en Alcalali"],"fave_pool":["Privado"],"fave_views":["Monta\u00f1a"],"_wp_page_template":["default"],"_thumbnail_id":["31722"],"fave_property_images":["1227","1228","1230","1231","1226","1229"],"_alp_processed":["1778368559"],"_wpml_word_count":["91"],"houzez_total_property_views":["22"],"houzez_views_by_date":["a:4:{s:10:\"05-10-2026\";i:6;s:10:\"05-11-2026\";i:4;s:10:\"05-12-2026\";i:8;s:10:\"05-13-2026\";i:4;}"],"houzez_recently_viewed":["2026-05-13 12:27:45"],"_elementor_page_assets":["a:0:{}"]},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>6461ALC Moderno chalet de nueva construcci\u00f3n de una sola planta en venta en Alcalali<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/costablancabuyers.com\/es\/property\/6461alc-villa-en-alcalali\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"6461ALC Moderno chalet de nueva construcci\u00f3n de una sola planta en venta en Alcalali\" \/>\n<meta property=\"og:description\" content=\"Este precioso chalet de una sola planta de nueva construcci\u00f3n est\u00e1 situado en una zona tranquila de una urbanizaci\u00f3n de Alcalali. Por un lado, el chalet ofrece un amplio sal\u00f3n con zona de comedor, una cocina moderna totalmente equipada y un lavadero. En el otro lado est\u00e1n los 2 dormitorios dobles, un cuarto de ba\u00f1o [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/costablancabuyers.com\/es\/property\/6461alc-villa-en-alcalali\/\" \/>\n<meta property=\"og:site_name\" content=\"Costa Blanca Buyers by Yohanne &amp; Jacqueline\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-09T23:15:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/costablancabuyers.com\/wp-content\/uploads\/2026\/01\/6461ALC1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1366\" \/>\n\t<meta property=\"og:image:height\" content=\"764\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"6461ALC Moderno chalet de nueva construcci\u00f3n de una sola planta en venta en Alcalali\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/costablancabuyers.com\\\/es\\\/property\\\/6461alc-villa-en-alcalali\\\/\",\"url\":\"https:\\\/\\\/costablancabuyers.com\\\/es\\\/property\\\/6461alc-villa-en-alcalali\\\/\",\"name\":\"6461ALC Moderno chalet de nueva construcci\u00f3n de una sola planta en venta en Alcalali\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/costablancabuyers.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/costablancabuyers.com\\\/es\\\/property\\\/6461alc-villa-en-alcalali\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/costablancabuyers.com\\\/es\\\/property\\\/6461alc-villa-en-alcalali\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/costablancabuyers.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/6461ALC1.jpg\",\"datePublished\":\"2023-03-31T09:11:03+00:00\",\"dateModified\":\"2026-05-09T23:15:58+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/costablancabuyers.com\\\/es\\\/property\\\/6461alc-villa-en-alcalali\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/costablancabuyers.com\\\/es\\\/property\\\/6461alc-villa-en-alcalali\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/costablancabuyers.com\\\/es\\\/property\\\/6461alc-villa-en-alcalali\\\/#primaryimage\",\"url\":\"https:\\\/\\\/costablancabuyers.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/6461ALC1.jpg\",\"contentUrl\":\"https:\\\/\\\/costablancabuyers.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/6461ALC1.jpg\",\"width\":1366,\"height\":764},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/costablancabuyers.com\\\/es\\\/property\\\/6461alc-villa-en-alcalali\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/costablancabuyers.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Propiedades\",\"item\":\"https:\\\/\\\/costablancabuyers.com\\\/es\\\/property\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Villa en Alcalali\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/costablancabuyers.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/costablancabuyers.com\\\/es\\\/\",\"name\":\"Costa Blanca Buyers by Yohanne & Jacqueline\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/costablancabuyers.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/costablancabuyers.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/costablancabuyers.com\\\/es\\\/#organization\",\"name\":\"Costa Blanca Buyers by Yohanne & Jacqueline\",\"url\":\"https:\\\/\\\/costablancabuyers.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/costablancabuyers.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/costablancabuyers.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/logo.svg\",\"contentUrl\":\"https:\\\/\\\/costablancabuyers.com\\\/wp-content\\\/uploads\\\/2026\\\/01\\\/logo.svg\",\"width\":500,\"height\":500,\"caption\":\"Costa Blanca Buyers by Yohanne & Jacqueline\"},\"image\":{\"@id\":\"https:\\\/\\\/costablancabuyers.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"6461ALC Moderno chalet de nueva construcci\u00f3n de una sola planta en venta en Alcalali","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/costablancabuyers.com\/es\/property\/6461alc-villa-en-alcalali\/","og_locale":"es_ES","og_type":"article","og_title":"6461ALC Moderno chalet de nueva construcci\u00f3n de una sola planta en venta en Alcalali","og_description":"Este precioso chalet de una sola planta de nueva construcci\u00f3n est\u00e1 situado en una zona tranquila de una urbanizaci\u00f3n de Alcalali. Por un lado, el chalet ofrece un amplio sal\u00f3n con zona de comedor, una cocina moderna totalmente equipada y un lavadero. En el otro lado est\u00e1n los 2 dormitorios dobles, un cuarto de ba\u00f1o [&hellip;]","og_url":"https:\/\/costablancabuyers.com\/es\/property\/6461alc-villa-en-alcalali\/","og_site_name":"Costa Blanca Buyers by Yohanne &amp; Jacqueline","article_modified_time":"2026-05-09T23:15:58+00:00","og_image":[{"width":1366,"height":764,"url":"https:\/\/costablancabuyers.com\/wp-content\/uploads\/2026\/01\/6461ALC1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_title":"6461ALC Moderno chalet de nueva construcci\u00f3n de una sola planta en venta en Alcalali","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/costablancabuyers.com\/es\/property\/6461alc-villa-en-alcalali\/","url":"https:\/\/costablancabuyers.com\/es\/property\/6461alc-villa-en-alcalali\/","name":"6461ALC Moderno chalet de nueva construcci\u00f3n de una sola planta en venta en Alcalali","isPartOf":{"@id":"https:\/\/costablancabuyers.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/costablancabuyers.com\/es\/property\/6461alc-villa-en-alcalali\/#primaryimage"},"image":{"@id":"https:\/\/costablancabuyers.com\/es\/property\/6461alc-villa-en-alcalali\/#primaryimage"},"thumbnailUrl":"https:\/\/costablancabuyers.com\/wp-content\/uploads\/2026\/01\/6461ALC1.jpg","datePublished":"2023-03-31T09:11:03+00:00","dateModified":"2026-05-09T23:15:58+00:00","breadcrumb":{"@id":"https:\/\/costablancabuyers.com\/es\/property\/6461alc-villa-en-alcalali\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/costablancabuyers.com\/es\/property\/6461alc-villa-en-alcalali\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/costablancabuyers.com\/es\/property\/6461alc-villa-en-alcalali\/#primaryimage","url":"https:\/\/costablancabuyers.com\/wp-content\/uploads\/2026\/01\/6461ALC1.jpg","contentUrl":"https:\/\/costablancabuyers.com\/wp-content\/uploads\/2026\/01\/6461ALC1.jpg","width":1366,"height":764},{"@type":"BreadcrumbList","@id":"https:\/\/costablancabuyers.com\/es\/property\/6461alc-villa-en-alcalali\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/costablancabuyers.com\/es\/"},{"@type":"ListItem","position":2,"name":"Propiedades","item":"https:\/\/costablancabuyers.com\/es\/property\/"},{"@type":"ListItem","position":3,"name":"Villa en Alcalali"}]},{"@type":"WebSite","@id":"https:\/\/costablancabuyers.com\/es\/#website","url":"https:\/\/costablancabuyers.com\/es\/","name":"Costa Blanca Buyers by Yohanne & Jacqueline","description":"","publisher":{"@id":"https:\/\/costablancabuyers.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/costablancabuyers.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/costablancabuyers.com\/es\/#organization","name":"Costa Blanca Buyers by Yohanne & Jacqueline","url":"https:\/\/costablancabuyers.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/costablancabuyers.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/costablancabuyers.com\/wp-content\/uploads\/2026\/01\/logo.svg","contentUrl":"https:\/\/costablancabuyers.com\/wp-content\/uploads\/2026\/01\/logo.svg","width":500,"height":500,"caption":"Costa Blanca Buyers by Yohanne & Jacqueline"},"image":{"@id":"https:\/\/costablancabuyers.com\/es\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/costablancabuyers.com\/es\/wp-json\/wp\/v2\/properties\/30343","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/costablancabuyers.com\/es\/wp-json\/wp\/v2\/properties"}],"about":[{"href":"https:\/\/costablancabuyers.com\/es\/wp-json\/wp\/v2\/types\/property"}],"author":[{"embeddable":true,"href":"https:\/\/costablancabuyers.com\/es\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":0,"href":"https:\/\/costablancabuyers.com\/es\/wp-json\/wp\/v2\/properties\/30343\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/costablancabuyers.com\/es\/wp-json\/wp\/v2\/media\/31722"}],"wp:attachment":[{"href":"https:\/\/costablancabuyers.com\/es\/wp-json\/wp\/v2\/media?parent=30343"}],"wp:term":[{"taxonomy":"property_type","embeddable":true,"href":"https:\/\/costablancabuyers.com\/es\/wp-json\/wp\/v2\/property_type?post=30343"},{"taxonomy":"property_status","embeddable":true,"href":"https:\/\/costablancabuyers.com\/es\/wp-json\/wp\/v2\/property_status?post=30343"},{"taxonomy":"property_feature","embeddable":true,"href":"https:\/\/costablancabuyers.com\/es\/wp-json\/wp\/v2\/property_feature?post=30343"},{"taxonomy":"property_label","embeddable":true,"href":"https:\/\/costablancabuyers.com\/es\/wp-json\/wp\/v2\/property_label?post=30343"},{"taxonomy":"property_country","embeddable":true,"href":"https:\/\/costablancabuyers.com\/es\/wp-json\/wp\/v2\/property_country?post=30343"},{"taxonomy":"property_state","embeddable":true,"href":"https:\/\/costablancabuyers.com\/es\/wp-json\/wp\/v2\/property_state?post=30343"},{"taxonomy":"property_city","embeddable":true,"href":"https:\/\/costablancabuyers.com\/es\/wp-json\/wp\/v2\/property_city?post=30343"},{"taxonomy":"property_area","embeddable":true,"href":"https:\/\/costablancabuyers.com\/es\/wp-json\/wp\/v2\/property_area?post=30343"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}